{"id":439,"date":"2020-02-16T07:25:28","date_gmt":"2020-02-16T14:25:28","guid":{"rendered":"https:\/\/natzarimyahshua.org\/az\/?page_id=439"},"modified":"2020-02-21T20:53:25","modified_gmt":"2020-02-22T03:53:25","slug":"february-2020","status":"publish","type":"page","link":"https:\/\/natzarimyahshua.org\/az\/february-2020\/","title":{"rendered":"February 2020"},"content":{"rendered":"\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 1254px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/az\/wp-json\/wp\/v2\/pages\/439\"         data-lightbox-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=6&#038;tag=0&#038;theme_id=1&#038;shortcode_id=12&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Faz%2Fwp-json%2Fwp%2Fv2%2Fpages%2F439\"         data-gallery-id=\"6\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"12\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"6\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">            \t\t\t\t\t\t\t\t<div class=\"search_line bwg_tag_select_view\">\t\t\t\t\t\t\t\t <style>      #bwg_search_container_1_0 {\t\t\t\tmax-width: 330px;      }      <\/style>            <div class=\"bwg_search_container_1\" id=\"bwg_search_container_1_0\">        <div class=\"bwg_search_container_2\" id=\"bwg_search_container_2_0\">        <span class=\"bwg_search_input_container\">          <span class=\"bwg_search_loupe_container1 bwg-hidden\">             <i title=\"SEARCH...\" class=\"bwg-icon-search bwg_search\" onclick=\"bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', 0, '', 'album', 1)\"><\/i>          <\/span>          <input id=\"bwg_search_input_0\" class=\"bwg_search_input\" type=\"search\" onkeypress=\"bwg_key_press(this); return bwg_check_search_input_enter(this, event);\" name=\"bwg_search_0\" value=\"\" placeholder=\"Search\" \/>          <span class=\"bwg_search_reset_container bwg-hidden\">          <i title=\"Reset\" class=\"bwg-icon-times bwg_reset\" onclick=\"bwg_clear_search_input('0'); bwg_ajax(&#039;gal_front_form_0&#039;, &#039;0&#039;, &#039;bwg_thumbnails_0&#039;, 0, &#039;&#039;, &#039;album&#039;, 1) \"><\/i>        <\/span>          <input id=\"bwg_images_count_0\" class=\"bwg_search_input\" type=\"hidden\" name=\"bwg_images_count_0\" value=\"45\">            <span class=\"search_placeholder_title\" onclick=\"bwg_search_focus(this)\" >                <span class=\"bwg_search_loupe_container\">                  <i title=\"SEARCH...\" class=\"bwg-icon-search bwg_search\"><\/i>                <\/span>                <span style=\"font-size: 12px; font-family: Ubuntu;\">Search<\/span>          <\/span>        <\/span>        <\/div>      <\/div>      \t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t    <div data-max-count=\"5\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"6\"         data-lightbox-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=6&amp;tag=0&amp;theme_id=1&amp;shortcode_id=12&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Faz%2Fwp-json%2Fwp%2Fv2%2Fpages%2F439\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"153\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/1-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"153\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/1-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"152\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"152\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"151\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/3-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"151\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/3-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"150\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/4-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"150\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/4-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"149\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/5-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"149\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/5-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"148\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/6-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"148\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/6-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"147\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/7-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"147\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"146\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/8-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"146\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/8-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"145\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/9-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"145\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/9-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"144\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/10-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"144\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/10-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"143\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/11-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"143\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/11-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"142\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/12-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"142\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/12-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"141\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/13-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"141\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/13-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"140\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/14-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"140\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/14-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"139\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/15-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"139\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/15-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"138\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/16-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"138\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/16-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"137\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/17-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"137\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/17-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"136\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/18-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"136\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/18-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"135\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/19-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"135\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/19-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"134\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/20-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"134\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/20-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"133\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/21-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"133\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/21-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"132\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/22-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"132\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/22-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"131\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/23-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"131\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/23-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"130\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/24-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"130\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/24-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"129\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/25-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"129\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/25-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"128\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/26-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"128\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/26-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"127\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/27-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"127\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/27-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"126\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/28-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"126\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/28-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"125\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/29-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"125\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/29-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"124\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/30-3.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"124\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/30-3.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"123\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/31-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"123\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/31-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"122\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/32-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"122\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/32-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"121\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/33-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"121\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/33-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"120\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/34-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"120\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/34-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"119\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/35-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"119\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/35-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"118\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/36-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"118\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/36-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"117\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/37-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"117\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/37-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"116\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/38-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"116\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/38-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"115\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/39-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"115\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/39-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"114\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/40-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"114\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/40-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"113\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/41-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"113\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/41-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"112\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/42-1.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"112\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/42-1.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"111\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/29-4.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"111\"                   data-width=\"500\"                   data-height=\"458\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/29-4.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"110\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/31-2.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"110\"                   data-width=\"500\"                   data-height=\"367\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/31-2.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"109\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/32-2.jpg?bwg=1582343094\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"109\"                   data-width=\"500\"                   data-height=\"433\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/32-2.jpg?bwg=1582343094\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>              <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"935795678\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-439","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":3,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/439\/revisions"}],"predecessor-version":[{"id":715,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/439\/revisions\/715"}],"wp:attachment":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/media?parent=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}