{"id":433,"date":"2020-02-16T07:20:57","date_gmt":"2020-02-16T14:20:57","guid":{"rendered":"https:\/\/natzarimyahshua.org\/az\/?page_id=433"},"modified":"2023-02-28T13:50:48","modified_gmt":"2023-02-28T20:50:48","slug":"november-2019","status":"publish","type":"page","link":"https:\/\/natzarimyahshua.org\/az\/november-2019\/","title":{"rendered":"November 2019"},"content":{"rendered":"\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 1254px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/az\/wp-json\/wp\/v2\/pages\/433\"         data-lightbox-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=4&#038;tag=0&#038;theme_id=1&#038;shortcode_id=8&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Faz%2Fwp-json%2Fwp%2Fv2%2Fpages%2F433\"         data-gallery-id=\"4\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"8\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"4\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">            \t\t\t\t\t\t\t\t<div class=\"search_line bwg_tag_select_view\">\t\t\t\t\t\t\t\t <style>      #bwg_search_container_1_0 {\t\t\t\tmax-width: 330px;      }      <\/style>            <div class=\"bwg_search_container_1\" id=\"bwg_search_container_1_0\">        <div class=\"bwg_search_container_2\" id=\"bwg_search_container_2_0\">        <span class=\"bwg_search_input_container\">          <span class=\"bwg_search_loupe_container1 bwg-hidden\">             <i title=\"SEARCH...\" class=\"bwg-icon-search bwg_search\" onclick=\"bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', 0, '', 'album', 1)\"><\/i>          <\/span>          <input id=\"bwg_search_input_0\" class=\"bwg_search_input\" type=\"search\" onkeypress=\"bwg_key_press(this); return bwg_check_search_input_enter(this, event);\" name=\"bwg_search_0\" value=\"\" placeholder=\"Search\" \/>          <span class=\"bwg_search_reset_container bwg-hidden\">          <i title=\"Reset\" class=\"bwg-icon-times bwg_reset\" onclick=\"bwg_clear_search_input('0'); bwg_ajax(&#039;gal_front_form_0&#039;, &#039;0&#039;, &#039;bwg_thumbnails_0&#039;, 0, &#039;&#039;, &#039;album&#039;, 1) \"><\/i>        <\/span>          <input id=\"bwg_images_count_0\" class=\"bwg_search_input\" type=\"hidden\" name=\"bwg_images_count_0\" value=\"14\">            <span class=\"search_placeholder_title\" onclick=\"bwg_search_focus(this)\" >                <span class=\"bwg_search_loupe_container\">                  <i title=\"SEARCH...\" class=\"bwg-icon-search bwg_search\"><\/i>                <\/span>                <span style=\"font-size: 12px; font-family: Ubuntu;\">Search<\/span>          <\/span>        <\/span>        <\/div>      <\/div>      \t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t    <div data-max-count=\"5\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"4\"         data-lightbox-url=\"https:\/\/natzarimyahshua.org\/az\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=4&amp;tag=0&amp;theme_id=1&amp;shortcode_id=8&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Faz%2Fwp-json%2Fwp%2Fv2%2Fpages%2F433\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"92\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/29-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"92\"                   data-width=\"375\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/29-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"91\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/30-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"91\"                   data-width=\"500\"                   data-height=\"374\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/30-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"103\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/18-2.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"103\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/18-2.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"101\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/20-2.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"101\"                   data-width=\"500\"                   data-height=\"290\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/20-2.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"90\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/17-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"90\"                   data-width=\"500\"                   data-height=\"375\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/17-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"102\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/19-2.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"102\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/19-2.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"100\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/21-2.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"100\"                   data-width=\"363\"                   data-height=\"500\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/21-2.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"99\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/22-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"99\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/22-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"98\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/23-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"98\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/23-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"97\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/24-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"97\"                   data-width=\"500\"                   data-height=\"280\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/24-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"96\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/25-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"96\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/25-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"95\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/26-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"95\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/26-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"94\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/27-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"94\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/27-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"93\" href=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/28-1.jpg?bwg=1582342052\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0  lazy_loader \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0  bwg_lazyload \"                   data-id=\"93\"                   data-width=\"500\"                   data-height=\"281\"                   data-src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/28-1.jpg?bwg=1582342052\"                   src=\"https:\/\/natzarimyahshua.org\/az\/wp-content\/plugins\/photo-gallery\/images\/lazy_placeholder.gif\"                   alt=\"\"                   title=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>              <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1704667015\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Natzarim Yahshua Mikvah&#039;s   November 2019\" width=\"660\" height=\"371\" src=\"https:\/\/www.youtube.com\/embed\/vkG-QgLzcd4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-433","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/comments?post=433"}],"version-history":[{"count":6,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/433\/revisions"}],"predecessor-version":[{"id":5777,"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/pages\/433\/revisions\/5777"}],"wp:attachment":[{"href":"https:\/\/natzarimyahshua.org\/az\/wp-json\/wp\/v2\/media?parent=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}